{"id":1,"count":3,"description":"","link":"https:\/\/creative.designswebs.com\/familyofficenotary\/category\/uncategorized\/","name":"Uncategorized","slug":"uncategorized","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/creative.designswebs.com\/familyofficenotary\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/creative.designswebs.com\/familyofficenotary\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/creative.designswebs.com\/familyofficenotary\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/creative.designswebs.com\/familyofficenotary\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}